{"id":1021,"date":"2023-09-22T16:38:38","date_gmt":"2023-09-22T16:38:38","guid":{"rendered":"http:\/\/costajump.com\/jerez\/?page_id=1021"},"modified":"2023-09-22T17:55:56","modified_gmt":"2023-09-22T17:55:56","slug":"fiestas","status":"publish","type":"page","link":"https:\/\/costajump.com\/jerez\/fiestas\/","title":{"rendered":"Fiestas"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"sc_layouts sc_layouts_default sc_layouts_1030\">[vc_row][vc_column width=\"1\/2\" icons_position=\"left\"]<div class=\"sc_layouts_item\"><div  id=\"sc_price_1976316425\" \n\tclass=\"sc_price color_style_default sc_price_default  vc_custom_1768242715251\"><div class=\"sc_price_info\"><div class=\"sc_price_subtitle\">Xtrema<\/div><div class=\"sc_price_description\">domingo a jueves<\/div><div class=\"sc_price_price\"><span class=\"sc_price_value\">\u20ac16,5<\/span><span class=\"sc_price_label\">minimo 10 personas<\/span><\/div><div class=\"sc_price_details\">[vc_column_text]\r\n<ul class=\"trx_addons_list_plus\">\r\n \t<li style=\"text-align: left;\">Duraci\u00f3n de la fiesta 3 horas<\/li>\r\n \t<li style=\"text-align: left;\">15 minutos de preparacion<\/li>\r\n \t<li style=\"text-align: left;\">2 horas de Salto<\/li>\r\n \t<li style=\"text-align: left;\">45 minutos de Merienda<\/li>\r\n \t<li style=\"text-align: left;\">Acceso libre a todo el parque<\/li>\r\n \t<li style=\"text-align: left;\">Invitaciones para tus amigos<\/li>\r\n \t<li style=\"text-align: left;\">Mesa privada<\/li>\r\n \t<li style=\"text-align: left;\">Calcetines anti-deslizantes Costajump<\/li>\r\n \t<li style=\"text-align: left;\">Agua ilimitada<\/li>\r\n \t<li style=\"text-align: left;\">Zumo por persona<\/li>\r\n \t<li style=\"text-align: left;\">Bolsa de chuches<\/li>\r\n \t<li style=\"text-align: left;\">Bolsa de patatas<\/li>\r\n \t<li style=\"text-align: left;\">3 trozos de pizza o 1 perrito caliente p.p.<\/li>\r\n<\/ul>\r\n[\/vc_column_text]<\/div><\/div>\n<\/div><\/div>[\/vc_column][vc_column width=\"1\/2\" icons_position=\"left\"]<div class=\"sc_layouts_item\"><div  id=\"sc_price_2062986368\" \n\tclass=\"sc_price color_style_default sc_price_default  vc_custom_1768242733940\"><div class=\"sc_price_info\"><div class=\"sc_price_subtitle\">Xtrema<\/div><div class=\"sc_price_description\">viernes y sabado<\/div><div class=\"sc_price_price\"><span class=\"sc_price_value\">\u20ac17,5<\/span><span class=\"sc_price_label\">minimo 10 personas<\/span><\/div><div class=\"sc_price_details\">[vc_column_text]\r\n<ul class=\"trx_addons_list_plus\">\r\n \t<li style=\"text-align: left;\">Duraci\u00f3n de la fiesta 3 horas<\/li>\r\n \t<li style=\"text-align: left;\">15 minutos de preparacion<\/li>\r\n \t<li style=\"text-align: left;\">2 horas de Salto<\/li>\r\n \t<li style=\"text-align: left;\">45 minutos de Merienda<\/li>\r\n \t<li style=\"text-align: left;\">Acceso libre a todo el parque<\/li>\r\n \t<li style=\"text-align: left;\">Invitaciones para tus amigos<\/li>\r\n \t<li style=\"text-align: left;\">Mesa privada<\/li>\r\n \t<li style=\"text-align: left;\">Calcetines anti-deslizantes Costajump<\/li>\r\n \t<li style=\"text-align: left;\">Agua ilimitada<\/li>\r\n \t<li style=\"text-align: left;\">Zumo por persona<\/li>\r\n \t<li style=\"text-align: left;\">Bolsa de chuches<\/li>\r\n \t<li style=\"text-align: left;\">Bolsa de patatas<\/li>\r\n \t<li style=\"text-align: left;\">3 trozos de pizza o 1 perrito caliente p.p.<\/li>\r\n<\/ul>\r\n[\/vc_column_text]<\/div><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column icons_position=\"left\"][vc_column_text]\r\n\r\n<!-- \/wp:code -->[\/vc_column_text][\/vc_column][\/vc_row]<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1021","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/pages\/1021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/comments?post=1021"}],"version-history":[{"count":12,"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/pages\/1021\/revisions"}],"predecessor-version":[{"id":1078,"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/pages\/1021\/revisions\/1078"}],"wp:attachment":[{"href":"https:\/\/costajump.com\/jerez\/wp-json\/wp\/v2\/media?parent=1021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}