{"id":1023,"date":"2023-09-22T16:39:07","date_gmt":"2023-09-22T16:39:07","guid":{"rendered":"http:\/\/costajump.com\/doshermanas\/?page_id=1023"},"modified":"2023-09-22T19:40:19","modified_gmt":"2023-09-22T19:40:19","slug":"precios","status":"publish","type":"page","link":"https:\/\/costajump.com\/doshermanas\/precios\/","title":{"rendered":"Precios"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"sc_layouts sc_layouts_default sc_layouts_1029\">[vc_row][vc_column width=\"1\/3\" icons_position=\"left\" css=\".vc_custom_1695410591206{margin-top: 20px !important;margin-bottom: 20px !important;}\"]<div class=\"sc_layouts_item\"><div  id=\"sc_price_1728128653\" \n\tclass=\"sc_price color_style_default sc_price_default  vc_custom_1782148169015\"><div class=\"sc_price_info\"><div class=\"sc_price_subtitle\">Lunes a Jueves (No valido festivos \/ vacaciones \/ 22 junio a 9 septiembre)<\/div><div class=\"sc_price_description\">No incluye calcetines Costajump obligatorios<\/div><div class=\"sc_price_price\"><span class=\"sc_price_value\">\u20ac9<\/span><span class=\"sc_price_label\">por persona<\/span><\/div><div class=\"sc_price_details\">[vc_column_text]\r\n<ul class=\"trx_addons_list_plus\">\r\n \t<li style=\"text-align: left;\">Acceso libre 1 hora<\/li>\r\n \t<li style=\"text-align: left;\">Empieza cada hora en punto<\/li>\r\n \t<li style=\"text-align: left;\">\u20ac7 hora adicional (consecutiva)<\/li>\r\n \t<li>\u20ac5 media hora adicional (consecutiva)<\/li>\r\n \t<li><\/li>\r\n<\/ul>\r\n[\/vc_column_text]<\/div><\/div>\n<\/div><\/div>[\/vc_column][vc_column width=\"1\/3\" icons_position=\"left\" css=\".vc_custom_1695410749748{margin-top: 20px !important;margin-bottom: 20px !important;}\"]<div class=\"sc_layouts_item\"><div  id=\"sc_price_1315398605\" \n\tclass=\"sc_price color_style_default sc_price_default  vc_custom_1780558329858\"><div class=\"sc_price_info\"><div class=\"sc_price_subtitle\">Viernes a Domingo (+festivos \/ vacaciones)<\/div><div class=\"sc_price_description\">No incluye calcetines Costajump obligatorios<\/div><div class=\"sc_price_price\"><span class=\"sc_price_value\">\u20ac11<\/span><span class=\"sc_price_label\">por persona<\/span><\/div><div class=\"sc_price_details\">[vc_column_text]\r\n<ul class=\"trx_addons_list_plus\">\r\n \t<li style=\"text-align: left;\">Acceso libre 1 hora<\/li>\r\n \t<li style=\"text-align: left;\">Empieza cada hora en punto<\/li>\r\n \t<li style=\"text-align: left;\">\u20ac9 hora adicional (consecutiva)<\/li>\r\n \t<li>\u20ac7 media hora adicional (consecutiva)<\/li>\r\n \t<li><\/li>\r\n<\/ul>\r\n[\/vc_column_text]<\/div><\/div>\n<\/div><\/div>[\/vc_column][vc_column width=\"1\/3\" icons_position=\"left\" css=\".vc_custom_1695410756611{margin-top: 20px !important;margin-bottom: 20px !important;}\"]<div class=\"sc_layouts_item\"><div  id=\"sc_price_1982317428\" \n\tclass=\"sc_price color_style_default sc_price_default  vc_custom_1695411698807\"><div class=\"sc_price_info\"><div class=\"sc_price_subtitle\">Calcetines<\/div><div class=\"sc_price_description\">Calcetines Costajump anti-deslizantes<\/div><div class=\"sc_price_price\"><span class=\"sc_price_value\">\u20ac2,50<\/span><span class=\"sc_price_label\">Par<\/span><\/div><div class=\"sc_price_details\">[vc_column_text]\r\n<ul class=\"trx_addons_list_plus\">\r\n \t<li style=\"text-align: left;\">De uso obligatorio<\/li>\r\n \t<li style=\"text-align: left;\">Reutilizables<\/li>\r\n \t<li style=\"text-align: left;\">Por higiene y seguridad<\/li>\r\n<\/ul>\r\n[\/vc_column_text]<\/div><\/div>\n<\/div><\/div>[\/vc_column][vc_column icons_position=\"left\"]<div class=\"sc_layouts_item\"><div  id=\"sc_price_1424506770\" \n\tclass=\"sc_price color_style_default sc_price_default  vc_custom_1780558401225\"><div class=\"sc_price_info\"><div class=\"sc_price_subtitle\">Bono<\/div><div class=\"sc_price_description\">Bono 10 entradas<\/div><div class=\"sc_price_price\"><span class=\"sc_price_value\">\u20ac85<\/span><\/div><div class=\"sc_price_details\">[vc_column_text]\r\n<ul class=\"trx_addons_list_plus\">\r\n \t<li style=\"text-align: left;\">Valido todos los dias<\/li>\r\n \t<li style=\"text-align: left;\">Solo se puede comprar en mostrador<\/li>\r\n<\/ul>\r\n[\/vc_column_text]<\/div><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row]<\/div>[\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1023","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/pages\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":7,"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/pages\/1023\/revisions"}],"predecessor-version":[{"id":1123,"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/pages\/1023\/revisions\/1123"}],"wp:attachment":[{"href":"https:\/\/costajump.com\/doshermanas\/wp-json\/wp\/v2\/media?parent=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}